{"id":28,"count":20,"description":"","link":"https:\/\/renowngift.com\/cenderahati\/category\/mint-tin\/","name":"Mint Tin","slug":"mint-tin","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mint Tin Archives - Cenderahati Perkahwinan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/renowngift.com\/cenderahati\/category\/mint-tin\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mint Tin Archives - Cenderahati Perkahwinan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/renowngift.com\/cenderahati\/category\/mint-tin\/\" \/>\n<meta property=\"og:site_name\" content=\"Cenderahati Perkahwinan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/category\\\/mint-tin\\\/\",\"url\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/category\\\/mint-tin\\\/\",\"name\":\"Mint Tin Archives - Cenderahati Perkahwinan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/category\\\/mint-tin\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/category\\\/mint-tin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mint Tin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/#website\",\"url\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/\",\"name\":\"Cenderahati Perkahwinan\",\"description\":\"laman untuk pelbagai cenderahati perkahwinan &amp; door gift wedding murah\",\"publisher\":{\"@id\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/#organization\",\"name\":\"Cenderahati Perkahwinan\",\"url\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/RG_LOGO-300x80.png\",\"contentUrl\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/RG_LOGO-300x80.png\",\"width\":300,\"height\":80,\"caption\":\"Cenderahati Perkahwinan\"},\"image\":{\"@id\":\"https:\\\/\\\/renowngift.com\\\/cenderahati\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mint Tin Archives - Cenderahati Perkahwinan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/renowngift.com\/cenderahati\/category\/mint-tin\/","og_locale":"en_US","og_type":"article","og_title":"Mint Tin Archives - Cenderahati Perkahwinan","og_url":"https:\/\/renowngift.com\/cenderahati\/category\/mint-tin\/","og_site_name":"Cenderahati Perkahwinan","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/renowngift.com\/cenderahati\/category\/mint-tin\/","url":"https:\/\/renowngift.com\/cenderahati\/category\/mint-tin\/","name":"Mint Tin Archives - Cenderahati Perkahwinan","isPartOf":{"@id":"https:\/\/renowngift.com\/cenderahati\/#website"},"breadcrumb":{"@id":"https:\/\/renowngift.com\/cenderahati\/category\/mint-tin\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/renowngift.com\/cenderahati\/category\/mint-tin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/renowngift.com\/cenderahati\/"},{"@type":"ListItem","position":2,"name":"Mint Tin"}]},{"@type":"WebSite","@id":"https:\/\/renowngift.com\/cenderahati\/#website","url":"https:\/\/renowngift.com\/cenderahati\/","name":"Cenderahati Perkahwinan","description":"laman untuk pelbagai cenderahati perkahwinan &amp; door gift wedding murah","publisher":{"@id":"https:\/\/renowngift.com\/cenderahati\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/renowngift.com\/cenderahati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/renowngift.com\/cenderahati\/#organization","name":"Cenderahati Perkahwinan","url":"https:\/\/renowngift.com\/cenderahati\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/renowngift.com\/cenderahati\/#\/schema\/logo\/image\/","url":"https:\/\/renowngift.com\/cenderahati\/wp-content\/uploads\/2014\/03\/RG_LOGO-300x80.png","contentUrl":"https:\/\/renowngift.com\/cenderahati\/wp-content\/uploads\/2014\/03\/RG_LOGO-300x80.png","width":300,"height":80,"caption":"Cenderahati Perkahwinan"},"image":{"@id":"https:\/\/renowngift.com\/cenderahati\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/renowngift.com\/cenderahati\/wp-json\/wp\/v2\/categories\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renowngift.com\/cenderahati\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/renowngift.com\/cenderahati\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/renowngift.com\/cenderahati\/wp-json\/wp\/v2\/posts?categories=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}